{"id":1311,"date":"2019-08-24T12:08:27","date_gmt":"2019-08-24T15:08:27","guid":{"rendered":"https:\/\/conectaid.com.br\/?p=1311"},"modified":"2020-04-18T01:39:34","modified_gmt":"2020-04-18T04:39:34","slug":"caridade-ou-solidariedade-social","status":"publish","type":"post","link":"https:\/\/conectaid.com.br\/index.php\/2019\/08\/24\/caridade-ou-solidariedade-social\/","title":{"rendered":"Caridade \u00e9 gentileza"},"content":{"rendered":"\n<p>\n\npor <a href=\"https:\/\/osegredo.com.br\/author\/priscila-mattos\/\">Priscila Mattos<\/a><\/p>\n\n\n\n<p> \u00c9 muito comum confundirmos&nbsp;<strong>caridade<\/strong>&nbsp;com <strong>solidariedade<\/strong>&nbsp;social. Quando falamos em&nbsp;<strong>caridade<\/strong>, logo nos vem \u00e0 mente a doa\u00e7\u00e3o de bens materiais de uma forma individual ou coletiva. <\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Mas, sermos solid\u00e1rios n\u00e3o \u00e9 o mesmo que sermos caridosos. <\/p>\n\n\n\n<p>A solidariedade \u00e9 um est\u00edmulo, uma maneira maravilhosa de express\u00e3o do bem, para tornar o ambiente em que vivemos um local menos desigual, socialmente falando. J\u00e1 a caridade, vai al\u00e9m\u2026 A caridade vem de dentro e, normalmente, \u00e9 invis\u00edvel perante os olhos da sociedade.<\/p>\n\n\n\n<p>\u00c0s vezes n\u00e3o \u00e9 nem percept\u00edvel para quem j\u00e1 a faz de maneira natural, e impercept\u00edvel tamb\u00e9m, apesar de muito trabalhosa, para aqueles que a fazem em sil\u00eancio, no \u00e1rduo processo de reforma \u00edntima.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/osegredo.com.br\/wp-content\/uploads\/2016\/11\/CARIDADE-OU-SOLIDARIEDADE-SOCIAL-capa-e-foto-01-.jpg\" alt=\"caridade-ou-solidariedade-social-capa-e-foto-01\" class=\"wp-image-87739\"\/><\/figure><\/div>\n\n\n\n<p>Caridade \u00e9 gentileza, \u00e9 sorrir num simples bom dia, boa tarde ou boa noite, mesmo que a gente se sinta p\u00e9ssimo por dentro, por n\u00e3o querermos contagiar negativamente os outros com nossos problemas; \u00e9 ficarmos quietos quando tivermos vontade de retrucar uma ofensa; \u00e9 sentirmos compaix\u00e3o ao inv\u00e9s de raiva; \u00e9 n\u00e3o falarmos mal da vida alheia, mesmo quando a \u201cl\u00edngua co\u00e7ar\u201d, \u00e9 conseguirmos fazer a fofoca morrer em n\u00f3s; \u00e9 elogiar ao inv\u00e9s de julgar ou simplesmente n\u00e3o falar quando n\u00e3o h\u00e1 nada bom a dizer; \u00e9 ter sensibilidade; \u00e9 n\u00e3o disseminar disc\u00f3rdia e sim harmonia; \u00e9 n\u00e3o matar sonhos alheios, \u00e9 enxergar o bem sempre, mesmo quando ele estiver bastante escondido; \u00e9 conseguir reparar os pr\u00f3prios erros e perdoar os erros pelos outros cometidos.<\/p>\n\n\n\n<p>A solidariedade modifica o ambiente exterior, tornando o mundo um lugar melhor para viver, mas n\u00e3o deve ser confundida com caridade, que \u00e9 uma modifica\u00e7\u00e3o do universo interior refletida em singelos gestos cotidianos, que n\u00e3o espera recompensas (nem divina), nem agradecimentos. Caridade \u00e9 simplesmente aceitar as pessoas como elas s\u00e3o, \u00e9 fazer prevalecer a raz\u00e3o quando o instinto falar alto, \u00e9 carinho (\u201ctocar o mundo do outro com respeito\u201d), \u00e9 olhar com os olhos da alma, sem interfer\u00eancia do pr\u00f3prio ego. \u00c9 desde sorrir de uma piada sem gra\u00e7a para dar a gra\u00e7a, at\u00e9 se afastar de quem ama para libertar. Caridade n\u00e3o \u00e9 doar o que tem, \u00e9 se doar\u2026 Caridade \u00e9 amar.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img alt=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>por Priscila Mattos \u00c9 muito comum confundirmos&nbsp;caridade&nbsp;com solidariedade&nbsp;social. Quando falamos em&nbsp;caridade, logo nos vem \u00e0 mente a doa\u00e7\u00e3o de bens materiais de uma forma individual ou coletiva. Mas, sermos solid\u00e1rios n\u00e3o \u00e9 o mesmo que sermos caridosos. A solidariedade \u00e9 um est\u00edmulo, uma maneira maravilhosa de express\u00e3o do bem, para tornar o ambiente em que&#8230; <a class=\"view-article\" href=\"https:\/\/conectaid.com.br\/index.php\/2019\/08\/24\/caridade-ou-solidariedade-social\/\">Ver artigo<\/a><\/p>\n","protected":false},"author":1,"featured_media":1432,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1311"}],"collection":[{"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1311"}],"version-history":[{"count":9,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1311\/revisions"}],"predecessor-version":[{"id":2327,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1311\/revisions\/2327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/media\/1432"}],"wp:attachment":[{"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conectaid.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}